{"id":6693,"date":"2025-12-13T13:53:36","date_gmt":"2025-12-13T05:53:36","guid":{"rendered":"https:\/\/www.ahkfjx.com\/?post_type=product&#038;p=6693"},"modified":"2025-12-15T15:27:12","modified_gmt":"2025-12-15T07:27:12","slug":"side-opening-plastic-crusher","status":"publish","type":"product","link":"https:\/\/www.ahkfjx.com\/de\/product\/side-opening-plastic-crusher\/","title":{"rendered":"Seitlich \u00f6ffnender Kunststoffbrecher"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6693\" class=\"elementor elementor-6693\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ddf7908 e-flex e-con-boxed e-con e-parent\" data-id=\"ddf7908\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98c2eaf elementor-widget elementor-widget-heading\" data-id=\"98c2eaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einf\u00fchrung in den seitlich \u00f6ffnenden Kunststoffzerkleinerer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e317d54 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e317d54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ef8206 elementor-widget elementor-widget-text-editor\" data-id=\"4ef8206\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der seitlich zu \u00f6ffnende Kunststoffzerkleinerer unterst\u00fctzt zwei Beschickungsmodi: Er kann entweder Materialien in Chargen durch die herk\u00f6mmliche Beschickungs\u00f6ffnung zuf\u00fchren oder eine pr\u00e4zise Beschickung \u00fcber das seitliche Beschickungsrohr erreichen. Die beiden Modi k\u00f6nnen flexibel umgeschaltet werden, so dass sie sich an unterschiedliche Materialformen und Betriebsanforderungen anpassen lassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-675c03a elementor-widget elementor-widget-image\" data-id=\"675c03a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"596\" height=\"447\" src=\"https:\/\/www.ahkfjx.com\/wp-content\/uploads\/2025\/12\/689f044278e790eabd320bbfc16eb803.png\" class=\"attachment-full size-full wp-image-6684\" alt=\"Brecher Detail\" srcset=\"https:\/\/www.ahkfjx.com\/wp-content\/uploads\/2025\/12\/689f044278e790eabd320bbfc16eb803.png 596w, https:\/\/www.ahkfjx.com\/wp-content\/uploads\/2025\/12\/689f044278e790eabd320bbfc16eb803-300x225.png 300w, https:\/\/www.ahkfjx.com\/wp-content\/uploads\/2025\/12\/689f044278e790eabd320bbfc16eb803-16x12.png 16w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94970c3 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"94970c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Merkmale des seitlich \u00f6ffnenden Kunststoffzerkleinerers\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f228f54 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f228f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6100ea0 elementor-widget elementor-widget-heading\" data-id=\"6100ea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Dual-Mode-F\u00fctterung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-750173c elementor-widget elementor-widget-text-editor\" data-id=\"750173c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unterst\u00fctzt sowohl die Chargenzuf\u00fchrung als auch die pr\u00e4zise Zuf\u00fchrung durch ein Seitenrohr, so dass die Bediener leicht zwischen den Modi wechseln k\u00f6nnen. Diese Flexibilit\u00e4t gew\u00e4hrleistet eine effiziente Handhabung unterschiedlicher Produktionsanforderungen ohne Unterbrechung des Arbeitsablaufs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9df28f1 elementor-widget elementor-widget-heading\" data-id=\"9df28f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Flexibler Betrieb<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a7380e elementor-widget elementor-widget-text-editor\" data-id=\"9a7380e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Passt sich an verschiedene Materialformen, -gr\u00f6\u00dfen und -volumina an und ist somit f\u00fcr unterschiedliche industrielle Anforderungen geeignet. Der Brecher kann Materialien unabh\u00e4ngig von ihrer L\u00e4nge oder Dicke gleichm\u00e4\u00dfig verarbeiten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a90ec9 elementor-widget elementor-widget-heading\" data-id=\"4a90ec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Hoher Wirkungsgrad<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e096b66 elementor-widget elementor-widget-text-editor\" data-id=\"e096b66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die optimierte Konstruktion der Brechkammer verhindert Materialverstopfungen und erm\u00f6glicht einen kontinuierlichen Betrieb. Auch bei starker Beanspruchung bleibt die Leistung stabil, was die Ausfallzeiten reduziert und die Produktivit\u00e4t erh\u00f6ht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab83b8 elementor-widget elementor-widget-heading\" data-id=\"6ab83b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Benutzerfreundliches Design<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d18532b elementor-widget elementor-widget-text-editor\" data-id=\"d18532b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Kombination aus einem seitlichen Zuf\u00fchrungsrohr und einem herk\u00f6mmlichen Trichter vereinfacht die Materialbeschickung, verbessert den Arbeitsablauf und verringert den Arbeitsaufwand. Die Bediener k\u00f6nnen das Material mit minimaler Einstellung oder \u00dcberwachung zuf\u00fchren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a54acd9 elementor-widget elementor-widget-heading\" data-id=\"a54acd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technische Parameter des seitlich \u00f6ffnenden Kunststoffzerkleinerers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45e6ab8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"45e6ab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-947192e elementor-widget elementor-widget-tablepress-table\" data-id=\"947192e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tablepress-table.default\">\n\t\t\t\t\t\n<table id=\"tablepress-34\" class=\"tablepress tablepress-id-34\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Modell<\/th><th class=\"column-2\">PP400<\/th><th class=\"column-3\">PP500<\/th><th class=\"column-4\">PP600<\/th><th class=\"column-5\">PP700<\/th><th class=\"column-6\">PP800<\/th><th class=\"column-7\">PP960<\/th><th class=\"column-8\">PP1000<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Leistung (HP)<\/td><td class=\"column-2\">10<\/td><td class=\"column-3\">15\/20<\/td><td class=\"column-4\">20\/30<\/td><td class=\"column-5\">20\/30<\/td><td class=\"column-6\">30\/40\/50<\/td><td class=\"column-7\">50\/60\/75<\/td><td class=\"column-8\">50\/60<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Nummerntafel (PCS) [Bewegen]<\/td><td class=\"column-2\">12<\/td><td class=\"column-3\">15<\/td><td class=\"column-4\">18<\/td><td class=\"column-5\">21<\/td><td class=\"column-6\">24<\/td><td class=\"column-7\">27<\/td><td class=\"column-8\">30<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Nummernblatt (PCS) [Fest]<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">2<\/td><td class=\"column-4\">2<\/td><td class=\"column-5\">2<\/td><td class=\"column-6\">4<\/td><td class=\"column-7\">4<\/td><td class=\"column-8\">4<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Brechkammer (MM)<\/td><td class=\"column-2\">410\u00d7230<\/td><td class=\"column-3\">515\u00d7295<\/td><td class=\"column-4\">615\u00d7320<\/td><td class=\"column-5\">715\u00d7320<\/td><td class=\"column-6\">825\u00d7470<\/td><td class=\"column-7\">960\u00d7600<\/td><td class=\"column-8\">1025\u00d7470<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Brechleistung (KG\/H)<\/td><td class=\"column-2\">200-250<\/td><td class=\"column-3\">300-350<\/td><td class=\"column-4\">350-450<\/td><td class=\"column-5\">400-500<\/td><td class=\"column-6\">450-600<\/td><td class=\"column-7\">600-700<\/td><td class=\"column-8\">600-800<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Abmessungen L (MM)<\/td><td class=\"column-2\">1200<\/td><td class=\"column-3\">1435<\/td><td class=\"column-4\">1580<\/td><td class=\"column-5\">1610<\/td><td class=\"column-6\">1800<\/td><td class=\"column-7\">2000<\/td><td class=\"column-8\">1800<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Abmessungen W (MM)<\/td><td class=\"column-2\">850<\/td><td class=\"column-3\">1100<\/td><td class=\"column-4\">1100<\/td><td class=\"column-5\">1210<\/td><td class=\"column-6\">2000<\/td><td class=\"column-7\">2200<\/td><td class=\"column-8\">1800<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Abmessungen H (MM)<\/td><td class=\"column-2\">1340<\/td><td class=\"column-3\">1550<\/td><td class=\"column-4\">1650<\/td><td class=\"column-5\">1740<\/td><td class=\"column-6\">2340<\/td><td class=\"column-7\">2340<\/td><td class=\"column-8\">2700<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Gewicht (KG)<\/td><td class=\"column-2\">500<\/td><td class=\"column-3\">900<\/td><td class=\"column-4\">1100<\/td><td class=\"column-5\">1100<\/td><td class=\"column-6\">2000<\/td><td class=\"column-7\">2500<\/td><td class=\"column-8\">3000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-34 from cache -->\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59d5dd1 elementor-widget elementor-widget-heading\" data-id=\"59d5dd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anwendung der seitlich \u00f6ffnenden Kunststoffzerkleinerungsmaschine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b1415e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3b1415e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa695fd elementor-widget elementor-widget-text-editor\" data-id=\"aa695fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong data-start=\"1250\" data-end=\"1286\">Kunststoff- und Profilrecycling<\/strong><br data-start=\"1286\" data-end=\"1289\" \/>Der seitlich \u00f6ffnende Kunststoffzerkleinerer ist ideal f\u00fcr Recyclinganlagen und verarbeitet effizient Kunststoffe, Kunststoffprofile und Verbundstoffabf\u00e4lle. Die zwei Beschickungsmodi erm\u00f6glichen eine pr\u00e4zise Steuerung der Zufuhr und optimieren den Durchsatz.<\/li><li><strong data-start=\"1494\" data-end=\"1543\">Herstellung von Holz-Kunststoff-Verbundstoffen (WPC)<\/strong><br data-start=\"1543\" data-end=\"1546\" \/>In der WPC-Produktion verarbeitet der Zerkleinerer Platten und Profile unterschiedlicher Gr\u00f6\u00dfe. Seine flexible Beschickung sorgt f\u00fcr eine reibungslose Verarbeitung langer oder unregelm\u00e4\u00dfiger St\u00fccke, reduziert den Abfall und bereitet das Material f\u00fcr die Wiederverwendung vor.<\/li><li><strong data-start=\"1752\" data-end=\"1786\">Industrielle Schrottverarbeitung<\/strong><br data-start=\"1786\" data-end=\"1789\" \/>Fabriken, die gemischte Schrottgr\u00f6\u00dfen produzieren, k\u00f6nnen sich auf den seitlich \u00f6ffnenden Kunststoffzerkleinerer f\u00fcr die R\u00fcckgewinnung gro\u00dfer Mengen verlassen. Die duale Beschickung gew\u00e4hrleistet einen kontinuierlichen Betrieb und minimale Ausfallzeiten.<\/li><li><strong data-start=\"1965\" data-end=\"2010\">Vorverarbeitung f\u00fcr Strangpressen und Formen<\/strong><br data-start=\"2010\" data-end=\"2013\" \/>Der Zerkleinerer bereitet das Rohmaterial f\u00fcr die Formgebung oder Extrusion vor, indem er gro\u00dfe Platten oder Profile auf handliche Gr\u00f6\u00dfen reduziert. Die pr\u00e4zise Seitenbeschickung tr\u00e4gt dazu bei, einen gleichm\u00e4\u00dfigen Materialfluss f\u00fcr die nachfolgende Produktion zu gew\u00e4hrleisten.<\/li><li><strong data-start=\"2223\" data-end=\"2267\">Werkstatt und kundenspezifisches Materialhandling<\/strong><br data-start=\"2267\" data-end=\"2270\" \/>Kleine und mittlere Betriebe profitieren von den flexiblen Beschickungsoptionen des Brechers. Je nach Materialart und Verarbeitungsbedarf kann der Bediener zwischen chargenweiser und pr\u00e4ziser Beschickung w\u00e4hlen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-559e9ae elementor-widget elementor-widget-heading\" data-id=\"559e9ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03ce2fc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"03ce2fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35e464e e-con-full e-flex e-con e-child\" data-id=\"35e464e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6745838 elementor-widget elementor-widget-n-accordion\" data-id=\"6745838\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Akkordeon. \u00d6ffnen Sie Links mit Enter oder Space, schlie\u00dfen Sie sie mit Escape und navigieren Sie mit den Pfeiltasten.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1080\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1080\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Welche Materialien kann der Kunststoffzerkleinerer mit Seiten\u00f6ffnung verarbeiten? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1080\" class=\"elementor-element elementor-element-da01471 e-con-full e-flex e-con e-child\" data-id=\"da01471\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c577c6f elementor-widget elementor-widget-text-editor\" data-id=\"c577c6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie verarbeitet Kunststoffe, Kunststoffprofile, Holz-Kunststoff-Verbundplatten und \u00e4hnliche Materialien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1081\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1081\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wie funktioniert die Dual-Mode-F\u00fctterung? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1081\" class=\"elementor-element elementor-element-c332f9b e-con-full e-flex e-con e-child\" data-id=\"c332f9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7136dee elementor-widget elementor-widget-text-editor\" data-id=\"7136dee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Material kann \u00fcber den Haupttrichter oder \u00fcber das seitliche Zuf\u00fchrungsrohr chargenweise zugef\u00fchrt werden. Das Umschalten zwischen den Modi ist schnell und bequem.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1082\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1082\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kann der seitlich \u00f6ffnende Kunststoffzerkleinerer lange oder unregelm\u00e4\u00dfige Materialien verarbeiten, ohne sich zu verklemmen? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1082\" class=\"elementor-element elementor-element-c8a4a2f e-con-full e-flex e-con e-child\" data-id=\"c8a4a2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1eeb29 elementor-widget elementor-widget-text-editor\" data-id=\"f1eeb29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ja, der seitlich zu \u00f6ffnende Kunststoffzerkleinerer ist so konzipiert, dass er auch bei langen oder sperrigen St\u00fccken reibungslos funktioniert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Introduction to the side-opening plastic crusher The side-opening plastic crusher supports dual-mode feeding: it can either feed materials in batches through the conventional feeding port or achieve precise feeding via the side feeding tube. The two modes can be switched flexibly, adapting to different material forms and operational requirements, and the operation is convenient and [&hellip;]<\/p>","protected":false},"author":8,"featured_media":6694,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"product-category":[13,20],"product-tag":[40],"class_list":["post-6693","product","type-product","status-publish","format-standard","has-post-thumbnail","hentry","product-category-crushing-and-recycling-equipment","product-category-heavy-duty-plastic-crusher","product-tag-shredding-and-recycling-line"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/product\/6693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":11,"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/product\/6693\/revisions"}],"predecessor-version":[{"id":6735,"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/product\/6693\/revisions\/6735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/media\/6694"}],"wp:attachment":[{"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/media?parent=6693"}],"wp:term":[{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/product-category?post=6693"},{"taxonomy":"product-tag","embeddable":true,"href":"https:\/\/www.ahkfjx.com\/de\/wp-json\/wp\/v2\/product-tag?post=6693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}